{"id":55807,"date":"2022-09-09T15:50:16","date_gmt":"2023-05-17T19:36:26","guid":{"rendered":"https:\/\/partners.exotiktours.com\/product\/portugal-long-sejour-luna-solaqua-4-albufeira\/"},"modified":"2026-07-03T09:36:01","modified_gmt":"2026-07-03T13:36:01","slug":"portugal-long-sejour-hotel-the-navigator-solaqua-albufeira","status":"publish","type":"product","link":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/","title":{"rendered":"Long s\u00e9jour au Portugal &#8211; h\u00f4tel The Navigator Solaqua 3.5*, Albufeira"},"content":{"rendered":"[vc_row][vc_column][vc_column_text]<figure id=\"attachment_35093\" aria-describedby=\"caption-attachment-35093\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-35093 size-large\"  src=\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2022\/09\/2267bf84ecd5f64e0a0f798248e6df7c.jpg\" alt=\"\" width=\"600\" srcset=\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2022\/09\/2267bf84ecd5f64e0a0f798248e6df7c.jpg 731w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2022\/09\/2267bf84ecd5f64e0a0f798248e6df7c-300x199.jpg 300w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2022\/09\/2267bf84ecd5f64e0a0f798248e6df7c-600x398.jpg 600w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2022\/09\/2267bf84ecd5f64e0a0f798248e6df7c-180x120.jpg 180w\" sizes=\"(max-width: 731px) 100vw, 731px\" \/><figcaption id=\"caption-attachment-35093\" class=\"wp-caption-text\">&nbsp;<\/figcaption><\/figure>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Le Portugal offre une vari\u00e9t\u00e9 de paysages \u00e0 d\u00e9couvrir ! Du bleu vif de la mer et de ses plages de sable blanc, au violet des vignobles en terrasse et \u00e0 ses magnifiques plaines verdoyantes, ce pays de contrastes vous assurera des vacances inoubliables. Offrant une gastronomie riche et vari\u00e9e, chaque r\u00e9gion du pays poss\u00e8de ses propres sp\u00e9cialit\u00e9s, dont la plupart s&rsquo;inspirent des produits locaux. La visite des ch\u00e2teaux, l&rsquo;admiration des cath\u00e9drales et l&rsquo;\u00e9l\u00e9gance classique des palais vous feront revivre le pass\u00e9. Le Portugal est depuis longtemps le choix incontest\u00e9 des amateurs de soleil.\n\rThe Navigator Solaqua est un apart-h\u00f4tel 3.5 \u00e9toiles situ\u00e9 au c\u0153ur de la pittoresque Albufeira, \u00e0 quelques pas du centre commercial Continente \/ Albufeira, avec un grand supermarch\u00e9, quelques restaurants et boutiques. Il est \u00e9galement tr\u00e8s bien plac\u00e9, \u00e0 10 minutes de marche du Strip (rue Oura) et de la vieille ville, ainsi que de magnifiques plages, comme Praia dos Pescadores et Praia do Inatel.\nL&rsquo;apart-h\u00f4tel propose des logements ind\u00e9pendants confortables, lumineux et spacieux, dot\u00e9s de la climatisation, d&rsquo;une connexion Wi-Fi gratuite et d&rsquo;un coffre-fort (\u20ac), ainsi que l&rsquo;acc\u00e8s \u00e0 une piscine int\u00e9rieure et ext\u00e9rieure.\n\nChaque unit\u00e9 comprend une t\u00e9l\u00e9vision \u00e0 \u00e9cran plat, une cuisinette bien \u00e9quip\u00e9e avec une cuisini\u00e8re \u00e9lectrique, un four \u00e0 micro-ondes et un r\u00e9frig\u00e9rateur, ainsi qu&rsquo;un grille-pain et une bouilloire. \n\n<br \/><h3>Inclus<\/h3>&#8211; Vols internationaux sur notre allocation de groupe, incluant les taxes a\u00e9roportuaires\n&#8211; 2 ou 3 nuits en h\u00e9bergement 4* \u00e0 Lisbonne (h\u00f4tel Smy ou similaire) avec petit d\u00e9jeuner \n&#8211; Un tour ville panoramique de Lisbonne de 3 heures (bilingue) \n&#8211; 21 ou 22 nuits en Algarve \u00e0 l&rsquo;h\u00f4tel The Navigator Solaqua 3.5* dans un studio avec cuisinette\n&#8211; Les transferts regroup\u00e9s \n&#8211; Un repr\u00e9sentant (anglophone) en Algarve pour assister et pour les excursions ($)<br \/><h3>Exclus<\/h3>Repas &#8211; Assurance voyage &#8211; Pourboires aux chauffeurs, guides, accompagnateurs &#8211; Excursions facultatives &#8211; Taxe touristique, payable directement \u00e0 l&rsquo;h\u00f4tel &#8211; Tout autre \u00e9l\u00e9ment non mentionn\u00e9 dans les inclusions.<br \/><h3>Informations Compl\u00e9mentaires<\/h3><h4>NON INCLUS : SELECTION DE SI\u00c8GES POUR LES GROUPES<\/h4><p>Concernant les s\u00e9lections de si\u00e8ges en contingent de groupe avec AIR CANADA :\nLes si\u00e8ges r\u00e9serv\u00e9s pour ce d\u00e9part font partie de notre allotement de groupe bloqu\u00e9 sur chaque avion. Dans ce cas, la s\u00e9lection des si\u00e8ges peut uniquement \u00eatre effectu\u00e9e directement \u00e0 l\u2019a\u00e9roport le jour du d\u00e9part, ou lors de l\u2019enregistrement en ligne 24 heures avant le d\u00e9part. Au moment de l\u2019\u00e9mission des billets, Exotik Tours informera la compagnie a\u00e9rienne des passagers voyageant ensemble dans un effort de faire en sorte que les si\u00e8ges soient c\u00f4te \u00e0 c\u00f4te. Toutefois, cela ne peut \u00eatre garanti \u00e0 l\u2019avance. Aucune exception aux r\u00e8gles de s\u00e9lection des si\u00e8ges n\u2019est permise dans le cadre de cette promotion et Exotik Tours ne peut \u00eatre tenu responsable de l\u2019attribution finale des si\u00e8ges \u00e0 bord de l\u2019avion.\n\r\rConcernant les s\u00e9lections de si\u00e8ges en contingent de groupe avec AIR TRANSAT :\nLa s\u00e9lection des si\u00e8ges avec Air Transat ne peut se faire que lorsque nous avons un minimum de 15 passagers inscrits.\n<\/p><br \/>[\/vc_column_text][\/vc_column][\/vc_row]","protected":false},"excerpt":{"rendered":"2 nuits \u00e0 Lisbonne et 21 ou 22 nuits en Algarve","protected":false},"featured_media":142339,"template":"","meta":[],"product_cat":[190],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Long s\u00e9jour au Portugal - h\u00f4tel The Navigator Solaqua 3.5*, Albufeira - Exotik Journeys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Long s\u00e9jour au Portugal - h\u00f4tel The Navigator Solaqua 3.5*, Albufeira - Exotik Journeys\" \/>\n<meta property=\"og:description\" content=\"2 nuits \u00e0 Lisbonne et 21 ou 22 nuits en Algarve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/\" \/>\n<meta property=\"og:site_name\" content=\"Exotik Journeys\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T13:36:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exotiktours.com\/wp-content\/uploads\/2025\/07\/cb093d67d64d4045d14334749acc4fdc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/exotiktours.com\/fr\/#organization\",\"name\":\"Exotik Journeys | Tours\",\"url\":\"https:\/\/exotiktours.com\/fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/exotiktours.com\/fr\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png\",\"contentUrl\":\"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png\",\"width\":512,\"height\":511,\"caption\":\"Exotik Journeys | Tours\"},\"image\":{\"@id\":\"https:\/\/exotiktours.com\/fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exotiktours.com\/fr\/#website\",\"url\":\"https:\/\/exotiktours.com\/fr\/\",\"name\":\"Exotik Journeys\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/exotiktours.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exotiktours.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2025\/07\/cb093d67d64d4045d14334749acc4fdc.jpg\",\"contentUrl\":\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2025\/07\/cb093d67d64d4045d14334749acc4fdc.jpg\",\"width\":900,\"height\":549},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#webpage\",\"url\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/\",\"name\":\"Long s\u00e9jour au Portugal - h\u00f4tel The Navigator Solaqua 3.5*, Albufeira - Exotik Journeys\",\"isPartOf\":{\"@id\":\"https:\/\/exotiktours.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#primaryimage\"},\"datePublished\":\"2023-05-17T19:36:26+00:00\",\"dateModified\":\"2026-07-03T13:36:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/exotiktours.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/partners.exotiktours.com\/fr\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Long s\u00e9jour au Portugal &#8211; h\u00f4tel The Navigator Solaqua 3.5*, Albufeira\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Long s\u00e9jour au Portugal - h\u00f4tel The Navigator Solaqua 3.5*, Albufeira - Exotik Journeys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/","og_locale":"fr_FR","og_type":"article","og_title":"Long s\u00e9jour au Portugal - h\u00f4tel The Navigator Solaqua 3.5*, Albufeira - Exotik Journeys","og_description":"2 nuits \u00e0 Lisbonne et 21 ou 22 nuits en Algarve","og_url":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/","og_site_name":"Exotik Journeys","article_modified_time":"2026-07-03T13:36:01+00:00","og_image":[{"width":900,"height":549,"url":"https:\/\/exotiktours.com\/wp-content\/uploads\/2025\/07\/cb093d67d64d4045d14334749acc4fdc.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/exotiktours.com\/fr\/#organization","name":"Exotik Journeys | Tours","url":"https:\/\/exotiktours.com\/fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/exotiktours.com\/fr\/#logo","inLanguage":"fr-FR","url":"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png","contentUrl":"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png","width":512,"height":511,"caption":"Exotik Journeys | Tours"},"image":{"@id":"https:\/\/exotiktours.com\/fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/exotiktours.com\/fr\/#website","url":"https:\/\/exotiktours.com\/fr\/","name":"Exotik Journeys","description":"","publisher":{"@id":"https:\/\/exotiktours.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exotiktours.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2025\/07\/cb093d67d64d4045d14334749acc4fdc.jpg","contentUrl":"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2025\/07\/cb093d67d64d4045d14334749acc4fdc.jpg","width":900,"height":549},{"@type":"WebPage","@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#webpage","url":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/","name":"Long s\u00e9jour au Portugal - h\u00f4tel The Navigator Solaqua 3.5*, Albufeira - Exotik Journeys","isPartOf":{"@id":"https:\/\/exotiktours.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#primaryimage"},"datePublished":"2023-05-17T19:36:26+00:00","dateModified":"2026-07-03T13:36:01+00:00","breadcrumb":{"@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/portugal-long-sejour-hotel-the-navigator-solaqua-albufeira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exotiktours.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/partners.exotiktours.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Long s\u00e9jour au Portugal &#8211; h\u00f4tel The Navigator Solaqua 3.5*, Albufeira"}]}]}},"_links":{"self":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product\/55807"}],"collection":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/media\/142339"}],"wp:attachment":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/media?parent=55807"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product_cat?post=55807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product_tag?post=55807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}