{"id":34487,"date":"2022-08-25T18:58:57","date_gmt":"2022-08-25T22:58:57","guid":{"rendered":"https:\/\/partners.exotiktours.com\/product\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/"},"modified":"2026-06-29T10:28:46","modified_gmt":"2026-06-29T14:28:46","slug":"croisiere-francophone-sur-le-mekong-vietnam-et-cambodge","status":"publish","type":"product","link":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/","title":{"rendered":"Croisi\u00e8re francophone Rivages du Monde &#8211; Au fil du M\u00e9kong"},"content":{"rendered":"[vc_row][vc_column][vc_column_text]<figure id=\"attachment_166223\" aria-describedby=\"caption-attachment-166223\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-166223 size-large\"  src=\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/4a46d2e8e36d6b83e6726a0798e21e28.jpg\" alt=\"\" width=\"600\" srcset=\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/4a46d2e8e36d6b83e6726a0798e21e28.jpg 900w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/4a46d2e8e36d6b83e6726a0798e21e28-300x202.jpg 300w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/4a46d2e8e36d6b83e6726a0798e21e28-768x517.jpg 768w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/4a46d2e8e36d6b83e6726a0798e21e28-600x404.jpg 600w, https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/4a46d2e8e36d6b83e6726a0798e21e28-180x120.jpg 180w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-166223\" class=\"wp-caption-text\">&nbsp;<\/figcaption><\/figure>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<h3>Le long ruban fertile de l\u2019Asie du Sud-Est<\/h3>\nN\u00e9 des neiges de la cha\u00eene himalayenne au Tibet, le M\u00e9kong, l\u2019un des plus grands fleuves d\u2019Asie, d\u00e9bute son irr\u00e9sistible course par la Chine du Sud. Sur plus de 4\u2009000 km, les gorges profondes du Yunnan, les quatre mille \u00eeles du Laos, les rizi\u00e8res d\u2019\u00e9meraude et le trafic incessant des embarcations au Vietnam composent les identit\u00e9s de ce fleuve-roi. En fin de course, en bordure de la mer de Chine, il s\u2019alanguit en un delta si vaste qu\u2019il pourrait \u00e0 lui seul \u00eatre un pays. Par les splendeurs monumentales des capitales successives de l\u2019ancien Royaume Khmer, par les langueurs ti\u00e8des de My Tho ou de Vinh Long, par la tr\u00e9pidante Cholon, quartier chinois de H\u00f4 Chi Minh-Ville, vous traverserez des mondes, empreints d\u2019une tradition ancestrale et d\u2019une modernit\u00e9 souriante. Au Cambodge, vous d\u00e9couvrirez l\u2019univers du bouddhisme theravada dans lequel les moines tiennent un r\u00f4le essentiel dans l\u2019organisation de la soci\u00e9t\u00e9, particuli\u00e8rement dans l\u2019enseignement, la sant\u00e9 et la justice. Au Vietnam, les cultes peuvent s\u2019associer : au bouddhisme mahayana se joint, particuli\u00e8rement dans la r\u00e9gion du delta, le culte des anc\u00eatres.\n\n<h3>Les points forts<\/h3>\n&#8211; Une croisi\u00e8re francophone encadr\u00e9e par un directeur de croisi\u00e8re Rivages du Monde\n&#8211; Toutes les excursions incluses\n&#8211; Un conf\u00e9rencier sp\u00e9cialiste \u00e0 Phnom Penh\n&#8211; Un itin\u00e9raire reliant des villes historiques (H\u00f4 Chi Minh-Ville, Phnom Penh et Angkor) en passant par les petites villes et villages traditionnels (Cai Be, \u00eele de la Soie\u2026)\n&#8211; Un itin\u00e9raire in\u00e9dit sur le M\u00e9kong Sup\u00e9rieur, plus sauvage et pr\u00e9serv\u00e9\n&#8211; Un bateau moderne, r\u00e9nov\u00e9, de grand confort de 32 cabines pour 64 passagers \n&#8211; Des cabines toutes \u00e9quip\u00e9es de balcons priv\u00e9s\n&#8211; Des boissons \u00e0 discr\u00e9tion \u00e0 bord : jus et sodas en canette, bi\u00e8re et alcools locaux, eau, th\u00e9, caf\u00e9\n&#8211; Le vin \u00e0 table pendant les repas\r\rItin\u00e9raire \u00e9galement disponible en sens inverse : de H\u00f4 Chi Minh-Ville \u00e0 Siem Reap.<br \/><h3>Inclus<\/h3>&#8211; L\u2019ensemble des transferts mentionn\u00e9s au programme\n&#8211; 2 nuits d&rsquo;h\u00e9bergement en h\u00f4tel 5* \u00e0 Siem Reap\n&#8211; 1 nuit d&rsquo;h\u00e9bergement en h\u00f4tel 5* \u00e0 Sa\u00efgon\n&#8211; 7 nuits \u00e0 bord du R\/V La Marguerite dans la cat\u00e9gorie choisie\n&#8211; 31 repas : 10 petits d\u00e9jeuners, 11 d\u00eeners et 10 soupers\n&#8211; Les boissons \u00e0 bord de la Marguerite : eau, boissons non alcoolis\u00e9es en canette, bi\u00e8res locales, th\u00e9, caf\u00e9 \u00e0 volont\u00e9 toute la journ\u00e9e, ainsi que le vin local pendant les repas\n&#8211; Les boissons lors des repas du s\u00e9jour \u00e0 Siem Reap et \u00e0 H\u00f4 Chi Minh-Ville : eau min\u00e9rale (50 cl \/pers.), th\u00e9 ou caf\u00e9\n&#8211; Une conf\u00e9rence \u00e0 bord lors de l\u2019escale \u00e0 Phnom Penh\n&#8211; 2 spectacles \u00e0 bord selon le programme\n&#8211; Les pourboires pour le personnel de bord du R\/V La Marguerite\n&#8211; L\u2019ensemble des visites et entr\u00e9es sur les sites mentionn\u00e9s au programme avec guide local francophone\n&#8211; Les services d\u2019un directeur de croisi\u00e8re francophone pendant toute la dur\u00e9e du voyage\n&#8211; Taxes portuaires<br \/><h3>Exclus<\/h3>Vols internationaux &#8211; Frais de visa si applicable &#8211; Boissons autres que celles mentionn\u00e9es &#8211; Pourboires pour les guides et les chauffeurs (55 USD \/ pers. recommand\u00e9s) &#8211; Repas autres que ceux mentionn\u00e9s &#8211; Assurance voyage &#8211; Tous les autres \u00e9l\u00e9ments non mentionn\u00e9s dans les inclusions.<br \/><h3>Informations Compl\u00e9mentaires<\/h3><h4>Remarque<\/h4><p><h4>EXTENSION POSSIBLE EN THAILANDE, AU VIETNAM OU AU CAMBODGE !<\/h4>\nContactez votre agent de voyage.\n\rD\u00e9part garantis avec un minimum de 45 passagers.<\/p><br \/>[\/vc_column_text][\/vc_column][\/vc_row]","protected":false},"excerpt":{"rendered":"Croisi\u00e8re francophone au Cambogde et au Vietnam","protected":false},"featured_media":166219,"template":"","meta":[],"product_cat":[],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Croisi\u00e8re francophone Rivages du Monde - Au fil du M\u00e9kong - Exotik Journeys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Croisi\u00e8re francophone Rivages du Monde - Au fil du M\u00e9kong - Exotik Journeys\" \/>\n<meta property=\"og:description\" content=\"Croisi\u00e8re francophone au Cambogde et au Vietnam\" \/>\n<meta property=\"og:url\" content=\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/\" \/>\n<meta property=\"og:site_name\" content=\"Exotik Journeys\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T14:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exotiktours.com\/wp-content\/uploads\/2026\/04\/569e3cc8b4b06eb9d12b5c33d8ff4bfe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/exotiktours.com\/fr\/#organization\",\"name\":\"Exotik Journeys | Tours\",\"url\":\"https:\/\/exotiktours.com\/fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/exotiktours.com\/fr\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png\",\"contentUrl\":\"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png\",\"width\":512,\"height\":511,\"caption\":\"Exotik Journeys | Tours\"},\"image\":{\"@id\":\"https:\/\/exotiktours.com\/fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exotiktours.com\/fr\/#website\",\"url\":\"https:\/\/exotiktours.com\/fr\/\",\"name\":\"Exotik Journeys\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/exotiktours.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exotiktours.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/569e3cc8b4b06eb9d12b5c33d8ff4bfe.jpg\",\"contentUrl\":\"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/569e3cc8b4b06eb9d12b5c33d8ff4bfe.jpg\",\"width\":900,\"height\":500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#webpage\",\"url\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/\",\"name\":\"Croisi\u00e8re francophone Rivages du Monde - Au fil du M\u00e9kong - Exotik Journeys\",\"isPartOf\":{\"@id\":\"https:\/\/exotiktours.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#primaryimage\"},\"datePublished\":\"2022-08-25T22:58:57+00:00\",\"dateModified\":\"2026-06-29T14:28:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/exotiktours.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/partners.exotiktours.com\/fr\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Croisi\u00e8re francophone Rivages du Monde &#8211; Au fil du M\u00e9kong\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Croisi\u00e8re francophone Rivages du Monde - Au fil du M\u00e9kong - Exotik Journeys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/","og_locale":"fr_FR","og_type":"article","og_title":"Croisi\u00e8re francophone Rivages du Monde - Au fil du M\u00e9kong - Exotik Journeys","og_description":"Croisi\u00e8re francophone au Cambogde et au Vietnam","og_url":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/","og_site_name":"Exotik Journeys","article_modified_time":"2026-06-29T14:28:46+00:00","og_image":[{"width":900,"height":500,"url":"https:\/\/exotiktours.com\/wp-content\/uploads\/2026\/04\/569e3cc8b4b06eb9d12b5c33d8ff4bfe.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/exotiktours.com\/fr\/#organization","name":"Exotik Journeys | Tours","url":"https:\/\/exotiktours.com\/fr\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/exotiktours.com\/fr\/#logo","inLanguage":"fr-FR","url":"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png","contentUrl":"https:\/\/exotiktours.com\/wp-content\/uploads\/2022\/01\/EXO2022-BIRD-En-Clr_EXO2022-En-Clr-square-512.png","width":512,"height":511,"caption":"Exotik Journeys | Tours"},"image":{"@id":"https:\/\/exotiktours.com\/fr\/#logo"}},{"@type":"WebSite","@id":"https:\/\/exotiktours.com\/fr\/#website","url":"https:\/\/exotiktours.com\/fr\/","name":"Exotik Journeys","description":"","publisher":{"@id":"https:\/\/exotiktours.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exotiktours.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/569e3cc8b4b06eb9d12b5c33d8ff4bfe.jpg","contentUrl":"https:\/\/partners.exotiktours.com\/wp-content\/uploads\/2026\/04\/569e3cc8b4b06eb9d12b5c33d8ff4bfe.jpg","width":900,"height":500},{"@type":"WebPage","@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#webpage","url":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/","name":"Croisi\u00e8re francophone Rivages du Monde - Au fil du M\u00e9kong - Exotik Journeys","isPartOf":{"@id":"https:\/\/exotiktours.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#primaryimage"},"datePublished":"2022-08-25T22:58:57+00:00","dateModified":"2026-06-29T14:28:46+00:00","breadcrumb":{"@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/partners.exotiktours.com\/fr\/voyages\/croisiere-francophone-sur-le-mekong-vietnam-et-cambodge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exotiktours.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/partners.exotiktours.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Croisi\u00e8re francophone Rivages du Monde &#8211; Au fil du M\u00e9kong"}]}]}},"_links":{"self":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product\/34487"}],"collection":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/media\/166219"}],"wp:attachment":[{"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/media?parent=34487"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product_cat?post=34487"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/partners.exotiktours.com\/fr\/wp-json\/wp\/v2\/product_tag?post=34487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}